{"id":51219,"date":"2024-09-20T09:44:11","date_gmt":"2024-09-20T07:44:11","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=51219"},"modified":"2024-09-20T09:44:11","modified_gmt":"2024-09-20T07:44:11","slug":"aprende-euskera-en-familia","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/aprende-euskera-en-familia\/","title":{"rendered":"\u00a1Aprende euskera en familia!"},"content":{"rendered":"<p>Desde nuestra <strong>Ikastola<\/strong>, este curso lanzamos una nueva iniciativa que nos hace especial ilusi\u00f3n: \u00a1ofrecemos <strong>cursos de euskera<\/strong> dirigidos a padres y madres! Queremos que tanto los que desean empezar desde cero como aquellas personas que buscan mejorar o conseguir un t\u00edtulo oficial puedan unirse. Habr\u00e1 clases desde el nivel <strong>A1 (inicial)<\/strong> hasta el <strong>C1 (avanzado)<\/strong>, adapt\u00e1ndonos a todos los niveles y necesidades.<\/p>\n<p>El objetivo es muy claro: <strong>favorecer el uso del euskera en casa<\/strong>. Sabemos que el camino hacia un hogar euskaldun empieza por las personas adultas, y por eso queremos dar ejemplo. As\u00ed podemos contribuir a crear un entorno en el que nuestro euskara viva y se transmita a las siguientes generaciones, que el euskera forme parte de la vida familiar. Desde las primeras palabras hasta conversaciones m\u00e1s complejas, todos pueden sumarse y avanzar a su ritmo.<\/p>\n<p>Aurrera!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde nuestra Ikastola, este curso lanzamos una nueva iniciativa que nos hace especial ilusi\u00f3n: \u00a1ofrecemos cursos de euskera dirigidos a padres y madres! Queremos que tanto los que desean empezar desde cero como aquellas personas que buscan mejorar o conseguir un t\u00edtulo oficial puedan unirse. Habr\u00e1 clases desde el nivel A1 (inicial) hasta el C1 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":51221,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[201],"class_list":["post-51219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escuela-de-padres","tag-euskara-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/51219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=51219"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/51219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/51221"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=51219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=51219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=51219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}