{"id":51975,"date":"2024-10-23T09:41:15","date_gmt":"2024-10-23T07:41:15","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=51975"},"modified":"2024-10-23T09:41:15","modified_gmt":"2024-10-23T07:41:15","slug":"nuestras-hijas-e-hijos-y-estudiantes-maestros-y-espejos","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/nuestras-hijas-e-hijos-y-estudiantes-maestros-y-espejos\/","title":{"rendered":"Nuestras hijas e hijos y estudiantes: maestros y espejos"},"content":{"rendered":"<p><strong>No podemos despertar su grandeza si no trabajamos nuestra propia grandeza. Son nuestro espejo y maestros en aquellas dificultades que tenemos como personas, como seres en desarrollo<\/strong>. \u00bfC\u00f3mo pedirles lo que nosotros no hacemos? <strong>Es importante trabajar en nuestro propio desarrollo, en la superaci\u00f3n de nuestros propios l\u00edmites, para ayudarles a superar los suyos<\/strong>. Y de esa manera, ambos nos desarrollamos en el camino. Ense\u00f1ar, es aprender dos veces. Hag\u00e1moslo. Demosle y demonos esa oportunidad.<\/p>\n<p>En definitiva nos pueden ense\u00f1ar a ver qu\u00e9 es lo importante, a identificar nuestros miedos, a salir de nuestra zona de confort, a buscar nuestras propias experiencias de aprendizaje y a crecer y desarrollarnos junto a ellas y ellos. Te dejamos un video que bien merece dedicarle unos minutos.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No podemos despertar su grandeza si no trabajamos nuestra propia grandeza. Son nuestro espejo y maestros en aquellas dificultades que tenemos como personas, como seres en desarrollo. \u00bfC\u00f3mo pedirles lo que nosotros no hacemos? Es importante trabajar en nuestro propio desarrollo, en la superaci\u00f3n de nuestros propios l\u00edmites, para ayudarles a superar los suyos. Y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":51976,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-51975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escuela-de-padres"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/51975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=51975"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/51975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/51976"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=51975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=51975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=51975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}