{"id":52292,"date":"2024-11-11T13:29:11","date_gmt":"2024-11-11T11:29:11","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=52292"},"modified":"2024-11-11T13:29:11","modified_gmt":"2024-11-11T11:29:11","slug":"inspirando-la-ciencia-los-estudiantes-de-3o-de-eso-reciben-a-un-investigador-de-biobizkaia-para-su-proyecto-stem","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/inspirando-la-ciencia-los-estudiantes-de-3o-de-eso-reciben-a-un-investigador-de-biobizkaia-para-su-proyecto-stem\/","title":{"rendered":"Inspirando la Ciencia: Los Estudiantes de 3\u00ba de ESO Reciben a un Investigador de Biobizkaia para su Proyecto STEM"},"content":{"rendered":"<p><strong>En 3\u00ba de ESO, nuestros estudiantes est\u00e1n inmersos en el desarrollo de un proyecto de investigaci\u00f3n en el \u00e1mbito STEM (Ciencia, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas). Este proyecto es una oportunidad \u00fanica para que se adentren en el fascinante mundo de la investigaci\u00f3n, desarrollando habilidades de pensamiento cr\u00edtico y cient\u00edfico mientras exploran temas de su inter\u00e9s en \u00e1reas clave para el futuro.<\/strong><\/p>\n<p>La semana pasada, tuvieron la suerte de contar con la visita de un <strong>investigador de Biobizkaia<\/strong>, quien comparti\u00f3 su experiencia y les dio valiosas pautas para avanzar en sus propios proyectos. Durante la sesi\u00f3n, el investigador les habl\u00f3 de los retos y metodolog\u00edas de la investigaci\u00f3n cient\u00edfica, aport\u00e1ndoles ideas para definir sus preguntas de investigaci\u00f3n, dise\u00f1ar sus experimentos y validar sus resultados.<\/p>\n<p>Gracias a esta visita, los estudiantes no solo recibieron consejos pr\u00e1cticos, sino que tambi\u00e9n vivieron una experiencia inspiradora que les ayud\u00f3 a comprender el impacto real de la ciencia en nuestra sociedad. Adem\u00e1s, esta interacci\u00f3n directa con un profesional del \u00e1mbito cient\u00edfico les brind\u00f3 una visi\u00f3n clara de la importancia de la disciplina, el rigor y la \u00e9tica en el trabajo investigador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 3\u00ba de ESO, nuestros estudiantes est\u00e1n inmersos en el desarrollo de un proyecto de investigaci\u00f3n en el \u00e1mbito STEM (Ciencia, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas). Este proyecto es una oportunidad \u00fanica para que se adentren en el fascinante mundo de la investigaci\u00f3n, desarrollando habilidades de pensamiento cr\u00edtico y cient\u00edfico mientras exploran temas de su inter\u00e9s [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":52293,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[302],"tags":[454,455],"class_list":["post-52292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alianzas","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/52292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=52292"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/52292\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/52293"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=52292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=52292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=52292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}