{"id":53415,"date":"2025-01-07T14:13:45","date_gmt":"2025-01-07T12:13:45","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=53415"},"modified":"2025-01-07T14:18:41","modified_gmt":"2025-01-07T12:18:41","slug":"talento-literario-en-lauaxeta","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/talento-literario-en-lauaxeta\/","title":{"rendered":"\u00a1Talento Literario en Lauaxeta!"},"content":{"rendered":"<p>El pasado mes de diciembre, nuestras alumnas <strong>Izaro Pagalday y Nikole Etxebarria<\/strong> destacaron como ganadoras en el <strong>Concurso Literario de Amorebieta<\/strong>, <strong>un certamen que reuni\u00f3 a 213 estudiantes de la regi\u00f3n con un objetivo com\u00fan: dar voz a su creatividad a trav\u00e9s de la escritura.<\/strong><\/p>\n<p>Este concurso, celebrado anualmente, es una oportunidad \u00fanica para que j\u00f3venes talentos literarios se expresen y compartan sus ideas. Izaro y Nikole, con sus obras llenas de originalidad y sensibilidad, lograron sobresalir entre las numerosas propuestas, confirmando una vez m\u00e1s el potencial, el esfuerzo y la dedicaci\u00f3n de nuestra juventud.<\/p>\n<p>La literatura no solo desarrolla habilidades ling\u00fc\u00edsticas, sino que tambi\u00e9n permite reflexionar sobre la realidad, construir un pensamiento cr\u00edtico y transmitir emociones e ideas de manera profunda.<\/p>\n<p>Desde Lauaxeta, felicitamos de nuevo a Izaro y Nikole. Aurrera!<\/p>\n<p>Te dejamos con la noticia publicada en medios:<\/p>\n<p><a href=\"https:\/\/www.elcorreo.com\/bizkaia\/duranguesado\/213-alumnos-participan-concurso-literario-amorebieta-20241223223041-nt.html\">El Correo<\/a><\/p>\n<p><a href=\"https:\/\/www.durangon.com\/sociedad-artistico-cultural-zornoza-k-idazlan-lehiaketako-sariak-banatu-dira\/\">Duangon<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado mes de diciembre, nuestras alumnas Izaro Pagalday y Nikole Etxebarria destacaron como ganadoras en el Concurso Literario de Amorebieta, un certamen que reuni\u00f3 a 213 estudiantes de la regi\u00f3n con un objetivo com\u00fan: dar voz a su creatividad a trav\u00e9s de la escritura. Este concurso, celebrado anualmente, es una oportunidad \u00fanica para que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":53422,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[231,236],"tags":[454,455],"class_list":["post-53415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lauaxeta-en-los-medios","category-premios-y-reconocimientos","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/53415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=53415"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/53415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/53422"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=53415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=53415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=53415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}