{"id":54092,"date":"2025-02-12T12:08:43","date_gmt":"2025-02-12T10:08:43","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=54092"},"modified":"2025-02-12T12:09:22","modified_gmt":"2025-02-12T10:09:22","slug":"first-lego-league-innovacion-aprendizaje-y-diversion","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/first-lego-league-innovacion-aprendizaje-y-diversion\/","title":{"rendered":"FIRST LEGO League: Innovaci\u00f3n, aprendizaje y diversi\u00f3n"},"content":{"rendered":"<p><strong>Un a\u00f1o m\u00e1s, <\/strong><strong>Lauaxeta Ikastola<\/strong><strong> ha participado en la <\/strong><strong>FIRST LEGO League (FLL)<\/strong><strong>, un programa educativo internacional que fomenta el inter\u00e9s por la ciencia y la tecnolog\u00eda a trav\u00e9s de la rob\u00f3tica y la innovaci\u00f3n. Este evento desaf\u00eda a los estudiantes a dise\u00f1ar, construir y programar un <\/strong><strong>robot aut\u00f3nomo<\/strong><strong>, al tiempo que desarrollan un proyecto de investigaci\u00f3n para resolver un problema real.<\/strong><\/p>\n<p><strong>En este proceso, no solo aplican todo lo que han aprendido en el aula, sino que <\/strong><strong>experimentan de primera mano c\u00f3mo la tecnolog\u00eda y la creatividad pueden combinarse para encontrar soluciones innovadoras<\/strong><strong>.<\/strong><\/p>\n<h3><strong>Construcci\u00f3n, programaci\u00f3n y aprendizaje en equipo<\/strong><\/h3>\n<p>Para participar en la FLL, los equipos deben dise\u00f1ar y programar un robot, capaz de completar una serie de misiones dentro de un tablero tem\u00e1tico. Esto implica:<\/p>\n<p>\u2705 <strong>Dise\u00f1ar y ensamblar su propio robot<\/strong>, pensando en su estructura y funcionalidad.<br \/>\n\u2705 <strong>Programar sus movimientos y acciones<\/strong>, optimizando cada detalle para superar los desaf\u00edos.<br \/>\n\u2705 <strong>Aplicar conocimientos de ingenier\u00eda, f\u00edsica y matem\u00e1ticas<\/strong>, todo mientras se divierten.<\/p>\n<p>Pero <strong>FIRST LEGO League<\/strong> es mucho m\u00e1s que rob\u00f3tica. Tambi\u00e9n fomenta habilidades como el <strong>trabajo en equipo, la comunicaci\u00f3n y la resoluci\u00f3n de problemas<\/strong>, promoviendo valores esenciales como la colaboraci\u00f3n y el respeto.<\/p>\n<h3><strong>Aprender mientras se divierten<\/strong><\/h3>\n<p>En Lauaxeta Ikastola, creemos que el aprendizaje pr\u00e1ctico es la mejor forma de consolidar conocimientos. <strong>FLL convierte la educaci\u00f3n en una experiencia emocionante<\/strong>, donde nuestros alumnos desarrollan <strong>habilidades STEAM<\/strong> (Ciencia, Tecnolog\u00eda, Ingenier\u00eda, Arte y Matem\u00e1ticas) de manera din\u00e1mica y motivadora.<\/p>\n<p>Zorionak por vuestro esfuerzo, creatividad y pasi\u00f3n por la tecnolog\u00eda. \u00a1Seguimos apostando por la innovaci\u00f3n y el aprendizaje divertido! \ud83d\ude80\ud83e\udd16<\/p>\n<p>\ud83d\udd17 <strong>Mira el video sobre nuestra participaci\u00f3n en FLL:<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"FLL Euskadi-MONDRAGON 2025 -  Lauaxeta ikastola motorrak berotzen\" width=\"1150\" height=\"647\" src=\"https:\/\/www.youtube.com\/embed\/qkp03SFPDnw?start=41&#038;feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/www.lauaxeta.eus\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un a\u00f1o m\u00e1s, Lauaxeta Ikastola ha participado en la FIRST LEGO League (FLL), un programa educativo internacional que fomenta el inter\u00e9s por la ciencia y la tecnolog\u00eda a trav\u00e9s de la rob\u00f3tica y la innovaci\u00f3n. Este evento desaf\u00eda a los estudiantes a dise\u00f1ar, construir y programar un robot aut\u00f3nomo, al tiempo que desarrollan un proyecto [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":54093,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[221],"tags":[458,459],"class_list":["post-54092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-extraescolares-y-de-verano","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/54092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=54092"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/54092\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/54093"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=54092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=54092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=54092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}