{"id":54102,"date":"2025-02-12T13:13:34","date_gmt":"2025-02-12T11:13:34","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=54102"},"modified":"2025-02-12T13:17:17","modified_gmt":"2025-02-12T11:17:17","slug":"deportes-y-movimiento-ejercicio-y-diversion","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/deportes-y-movimiento-ejercicio-y-diversion\/","title":{"rendered":"Deporte y Movimiento: ejercicio, valores y diversi\u00f3n"},"content":{"rendered":"<p>El deporte es mucho m\u00e1s que actividad f\u00edsica: es trabajo en equipo, esfuerzo y diversi\u00f3n. En la ikastola, ofrecemos diferentes disciplinas para que cada cual encuentre la que m\u00e1s le motive.<\/p>\n<p>\ud83d\udef9 <strong>Skate en primaria<\/strong>: Desaf\u00eda la gravedad con equilibrio y estilo.<br \/>\n\ud83e\udd38\u200d\u2640\ufe0f <strong>Gimnasia r\u00edtmica en primaria<\/strong>: Coordinaci\u00f3n, flexibilidad y ritmo en cada movimiento.<br \/>\n\ud83e\udd4b <strong>Judo en primaria<\/strong>: Respeto, disciplina y autoconfianza.<br \/>\n\ud83c\udfca\u200d\u2642\ufe0f <strong>Nataci\u00f3n en infantil y primaria: <\/strong>Agua, autonom\u00eda y diversi\u00f3n<br \/>\n\ud83e\uddd8 <strong>\ud83d\ude0aYoga en primaria:<\/strong> equilibrio, bienestar y emociones.<br \/>\n\ud83c\udfc0 <strong>Baloncesto en infantil, primaria y secundaria<\/strong>: Estrategia, equipo y canastas inolvidables.<br \/>\n\u26bd <strong>F\u00fatbol en primaria y secundaria<\/strong>: Pasi\u00f3n y compa\u00f1erismo sobre el c\u00e9sped.<br \/>\n\ud83c\udfd2 <strong>Hockey en primaria<\/strong>: Velocidad y trabajo en equipo con stick en mano.<br \/>\n\ud83c\udfca\u200d\u2642\ufe0f <strong>Waterpolo en secundaria<\/strong>: Un desaf\u00edo acu\u00e1tico que combina nataci\u00f3n y estrategia.<\/p>\n<p>\ud83d\udcaa <strong>El deporte nos ense\u00f1a grandes valores para la vida<\/strong>. \u00bfQu\u00e9 deporte marc\u00f3 tu infancia? \ud83c\udfc6<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El deporte es mucho m\u00e1s que actividad f\u00edsica: es trabajo en equipo, esfuerzo y diversi\u00f3n. En la ikastola, ofrecemos diferentes disciplinas para que cada cual encuentre la que m\u00e1s le motive. \ud83d\udef9 Skate en primaria: Desaf\u00eda la gravedad con equilibrio y estilo. \ud83e\udd38\u200d\u2640\ufe0f Gimnasia r\u00edtmica en primaria: Coordinaci\u00f3n, flexibilidad y ritmo en cada movimiento. \ud83e\udd4b [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":54109,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[221],"tags":[],"class_list":["post-54102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-extraescolares-y-de-verano"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/54102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=54102"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/54102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/54109"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=54102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=54102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=54102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}