{"id":54356,"date":"2025-02-24T11:18:56","date_gmt":"2025-02-24T09:18:56","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=54356"},"modified":"2025-02-24T11:18:56","modified_gmt":"2025-02-24T09:18:56","slug":"exito-en-first-lego-league-dos-premios-para-nuestros-estudiantes","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/exito-en-first-lego-league-dos-premios-para-nuestros-estudiantes\/","title":{"rendered":"\u00c9xito en  First Lego League: Dos premios para nuestros estudiantes"},"content":{"rendered":"<p data-start=\"151\" data-end=\"517\"><strong data-start=\"154\" data-end=\"175\">First Lego League<\/strong> es mucho m\u00e1s que una competici\u00f3n de rob\u00f3tica; es un espacio donde la <strong data-start=\"245\" data-end=\"259\">innovaci\u00f3n<\/strong>, la <strong data-start=\"264\" data-end=\"279\">creatividad<\/strong> y el <strong data-start=\"285\" data-end=\"306\">trabajo en equipo<\/strong> se unen para afrontar retos reales mediante la ciencia y la tecnolog\u00eda. Este a\u00f1o, nuestros estudiantes no solo disfrutaron de la experiencia, sino que tambi\u00e9n brillaron, llev\u00e1ndose <strong data-start=\"488\" data-end=\"514\">dos premios destacados<\/strong>:<\/p>\n<p data-start=\"519\" data-end=\"696\">\ud83e\udd47 <strong data-start=\"522\" data-end=\"616\">Premio Arrasateko Udala &#8211; Etorkizun oparoko gazteentzat (J\u00f3venes con un futuro prometedor)<\/strong><br data-start=\"616\" data-end=\"619\" \/>\ud83e\udd47 <strong data-start=\"622\" data-end=\"694\">Premio Maier &#8211; Ingeniaritzan bikaintasuna (Excelencia en ingenier\u00eda)<\/strong><\/p>\n<p data-start=\"698\" data-end=\"1020\">El equipo ganador estuvo formado por <strong data-start=\"735\" data-end=\"923\">Ilargi Merino, Leire Fern\u00e1ndez, Uxue Medina, Aimar G\u00f3mez, Arai Areskurrinaga, Mikel Guti\u00e9rrez, Ager Izaola, Maddi D\u00edez, Gontzal Herranz, Aitor Castells, Amets Carrasco y Alize Bernaola<\/strong>, quienes demostraron su capacidad para innovar, colaborar y superar desaf\u00edos con gran ingenio.<\/p>\n<p data-start=\"1022\" data-end=\"1271\">Durante la competici\u00f3n, los y las estudiantes trabajaron en un <strong data-start=\"1085\" data-end=\"1111\">proyecto de innovaci\u00f3n<\/strong>, desarrollando una soluci\u00f3n creativa y sostenible para un reto actual, adem\u00e1s de dise\u00f1ar, construir y programar un robot capaz de superar diferentes pruebas.<\/p>\n<p data-start=\"1273\" data-end=\"1478\">Estos galardones no solo reconocen su <strong data-start=\"1311\" data-end=\"1333\">excelencia t\u00e9cnica<\/strong>, sino tambi\u00e9n su <strong data-start=\"1351\" data-end=\"1414\">compromiso, perseverancia y capacidad de trabajar en equipo<\/strong>, habilidades clave para su desarrollo personal y profesional.<\/p>\n<p data-start=\"1480\" data-end=\"1614\">\ud83d\udca1 <strong data-start=\"1483\" data-end=\"1609\">\u00a1Zorionak, ekipo! Este logro es el resultado de vuestro esfuerzo y pasi\u00f3n por el aprendizaje. \u00a1A seguir so\u00f1ando y creando!<\/strong> \ud83d\ude80<\/p>\n","protected":false},"excerpt":{"rendered":"<p>First Lego League es mucho m\u00e1s que una competici\u00f3n de rob\u00f3tica; es un espacio donde la innovaci\u00f3n, la creatividad y el trabajo en equipo se unen para afrontar retos reales mediante la ciencia y la tecnolog\u00eda. Este a\u00f1o, nuestros estudiantes no solo disfrutaron de la experiencia, sino que tambi\u00e9n brillaron, llev\u00e1ndose dos premios destacados: \ud83e\udd47 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":54357,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[221,236],"tags":[458,459],"class_list":["post-54356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-extraescolares-y-de-verano","category-premios-y-reconocimientos","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/54356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=54356"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/54356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/54357"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=54356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=54356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=54356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}