{"id":54617,"date":"2025-03-10T11:36:48","date_gmt":"2025-03-10T09:36:48","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=54617"},"modified":"2025-03-10T11:37:22","modified_gmt":"2025-03-10T09:37:22","slug":"txapeldunak-hazten-kirol-topaketa-berezia-lauaxetan","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/txapeldunak-hazten-kirol-topaketa-berezia-lauaxetan\/","title":{"rendered":"\u00a1Creciendo como campeones: Encuentro deportivo en Lauaxeta!"},"content":{"rendered":"<p data-start=\"120\" data-end=\"397\">Este fin de semana hemos celebrado en Lauaxeta Ikastola un evento muy especial: \u00a1el <strong data-start=\"204\" data-end=\"242\">Encuentro Deportivo de Txapeldunes<\/strong>! Y s\u00ed, hablamos de aut\u00e9nticos campeones, porque <strong data-start=\"291\" data-end=\"322\">nuestros peque\u00f1os de 5 a\u00f1os<\/strong> han demostrado su pasi\u00f3n por el deporte practicando f\u00fatbol y baloncesto.<\/p>\n<p data-start=\"399\" data-end=\"492\">Pero este encuentro no se trata solo de marcar goles o encestar canastas. <strong data-start=\"473\" data-end=\"489\">Es mucho m\u00e1s<\/strong>:<\/p>\n<p data-start=\"494\" data-end=\"864\">\u2705 <strong data-start=\"496\" data-end=\"517\">Trabajo en equipo<\/strong>: Aprenden a entenderse y apoyarse entre compa\u00f1eros.<br data-start=\"569\" data-end=\"572\" \/>\u2705 <strong data-start=\"574\" data-end=\"602\">Esfuerzo y perseverancia<\/strong>: Descubren la importancia de intentarlo, aprender de los errores y volver a levantarse.<br data-start=\"690\" data-end=\"693\" \/>\u2705 <strong data-start=\"695\" data-end=\"721\">Respeto y deportividad<\/strong>: Valoran a rivales, \u00e1rbitros y compa\u00f1eros con respeto.<br data-start=\"776\" data-end=\"779\" \/>\u2705 <strong data-start=\"781\" data-end=\"803\">Diversi\u00f3n y pasi\u00f3n<\/strong>: Disfrutan del deporte, se mueven y se lo pasan en grande.<\/p>\n<p data-start=\"866\" data-end=\"1047\">Es un orgullo ver c\u00f3mo <strong data-start=\"889\" data-end=\"919\">nuestros futuros campeones<\/strong> ya est\u00e1n interiorizando estos valores. \u00a1Gracias a todos los que hab\u00e9is participado y que siga la pasi\u00f3n por el deporte! \ud83d\udc9a\ud83c\udfc0\u26bd<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana hemos celebrado en Lauaxeta Ikastola un evento muy especial: \u00a1el Encuentro Deportivo de Txapeldunes! Y s\u00ed, hablamos de aut\u00e9nticos campeones, porque nuestros peque\u00f1os de 5 a\u00f1os han demostrado su pasi\u00f3n por el deporte practicando f\u00fatbol y baloncesto. Pero este encuentro no se trata solo de marcar goles o encestar canastas. Es [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":54618,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[408,434],"class_list":["post-54617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-hh-es","tag-infantil"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/54617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=54617"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/54617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/54618"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=54617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=54617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=54617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}