{"id":54879,"date":"2025-03-24T14:10:01","date_gmt":"2025-03-24T12:10:01","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=54879"},"modified":"2025-03-24T14:10:01","modified_gmt":"2025-03-24T12:10:01","slug":"celebramos-el-dia-del-agua-con-ilusion-y-conciencia","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/celebramos-el-dia-del-agua-con-ilusion-y-conciencia\/","title":{"rendered":"Celebramos el D\u00eda del Agua con ilusi\u00f3n y conciencia"},"content":{"rendered":"<p>Este viernes, con motivo del <strong>D\u00eda Mundial del Agua<\/strong>, nuestros estudiantes de <strong>Primaria<\/strong> han disfrutado de una jornada especial llena de aprendizaje y diversi\u00f3n. \ud83c\udf89\ud83c\udf0e<\/p>\n<p>\ud83d\udca6 <strong>Carrera de botes de nuez en nuestro riachuelo<\/strong>: Los m\u00e1s peque\u00f1os han puesto a prueba su creatividad y habilidad en una carrera \u00fanica con barquitos hechos con c\u00e1scaras de nuez. \u00a1Toda una aventura en miniatura para entender la importancia de los r\u00edos y el agua en nuestro entorno! \ud83c\udf3f\ud83d\udea3\u200d\u2642\ufe0f<\/p>\n<p>\ud83c\udfe1 <strong>\u00a1Reto sobre el agua para las familias!<\/strong> Nuestras familias tambi\u00e9n est\u00e1n participado en un reto especial relacionado con el agua. Porque cuidar este recurso tan valioso es tarea de todos. \ud83d\udc99\ud83c\udf0d<\/p>\n<p>Gracias a todos los que han formado parte de esta iniciativa. Juntos, seguimos aprendiendo y concienciando sobre el uso responsable del agua. \ud83d\udca6\ud83d\udc99<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este viernes, con motivo del D\u00eda Mundial del Agua, nuestros estudiantes de Primaria han disfrutado de una jornada especial llena de aprendizaje y diversi\u00f3n. \ud83c\udf89\ud83c\udf0e \ud83d\udca6 Carrera de botes de nuez en nuestro riachuelo: Los m\u00e1s peque\u00f1os han puesto a prueba su creatividad y habilidad en una carrera \u00fanica con barquitos hechos con c\u00e1scaras de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":54880,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[223],"tags":[458,459],"class_list":["post-54879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ods-y-agenda-2030","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/54879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=54879"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/54879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/54880"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=54879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=54879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=54879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}