{"id":54902,"date":"2025-03-25T10:26:33","date_gmt":"2025-03-25T08:26:33","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=54902"},"modified":"2025-03-25T10:26:33","modified_gmt":"2025-03-25T08:26:33","slug":"descubre-la-magia-de-la-ciencia-en-el-dia-stem-de-lauaxeta","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/descubre-la-magia-de-la-ciencia-en-el-dia-stem-de-lauaxeta\/","title":{"rendered":"\u00a1Descubre la magia de la ciencia en el D\u00eda STEM de Lauaxeta!"},"content":{"rendered":"<p>\u00bfQu\u00e9 tienen en com\u00fan un <strong>tornado en una botella<\/strong>, un <strong>camale\u00f3n qu\u00edmico<\/strong> y un <strong>reloj de yodo<\/strong>? \u00a1Que desaf\u00edan nuestra percepci\u00f3n y nos invitan a explorar el fascinante mundo de la ciencia! En Lauaxeta, celebramos el <strong>D\u00eda STEM<\/strong> con actividades que despiertan la curiosidad, fomentan el pensamiento cr\u00edtico y nos acercan a los grandes descubrimientos cient\u00edficos. \ud83e\udd13\ud83c\udf89<\/p>\n<p><strong>Experimentos y descubrimientos para todas las edades<\/strong><\/p>\n<p>Para el alumnado de <strong>Bachillerato<\/strong>, la jornada ha estado llena de desaf\u00edos cient\u00edficos, ya que han dinamizado <strong>talleres especiales para los y las m\u00e1s peque\u00f1as de Primaria<\/strong>. Entre las experiencias, destacan:<\/p>\n<p>\ud83c\udf2c\ufe0f <strong>Tornado en una botella<\/strong>: comprender los principios de la din\u00e1mica de fluidos de una forma visual y entretenida. \ud83e\udd8a\ud83d\udc09 <strong>Camale\u00f3n qu\u00edmico<\/strong>: observar reacciones qu\u00edmicas que cambian de color y aprender sobre la oxidaci\u00f3n y reducci\u00f3n. \ud83d\udd52 <strong>Reloj de yodo y sem\u00e1foro qu\u00edmico<\/strong>: reacciones con cambios de color temporizados que nos ense\u00f1an sobre la cin\u00e9tica qu\u00edmica. \ud83d\udc34\ud83e\udd67 <strong>Pasta de elefante<\/strong>: una reacci\u00f3n espectacular para entender la descomposici\u00f3n catal\u00edtica del per\u00f3xido de hidr\u00f3geno.<\/p>\n<p>Adem\u00e1s, las y los estudiantes han participado en el <strong>concurso de Casio \u00abBuscamos cient\u00edficas\u00bb<\/strong>, investigando sobre una <strong>mujer cient\u00edfica<\/strong> y represent\u00e1ndola en un dibujo. Tambi\u00e9n han creado su propio <strong>taumatropo<\/strong>, un juguete \u00f3ptico que nos permite descubrir los secretos de la <strong>persistencia retiniana<\/strong>. Y, se han acercado al valioso trabajo de muchas <strong>mujeres en el mundo de la ciencia<\/strong>. \ud83d\udc69\u200d\ud83d\udd2c\ud83d\udc68\u200d\ud83d\udd2c<\/p>\n<p>La <strong>magia y la ciencia<\/strong> tambi\u00e9n se han dado la mano con <strong>Imanol Itui\u00f1o<\/strong>, quien les ha sorprendido con su espect\u00e1culo, mostrando c\u00f3mo la <strong>ciencia y la magia<\/strong> pueden combinarse de forma asombrosa. \ud83c\udfab\u2728<\/p>\n<p>Todo esto lo hemos desarrollado gracias a la colaboraci\u00f3n del FECYT.<\/p>\n<p>\u00a1Un d\u00eda repleto de <strong>descubrimientos, experimentos y mucha diversi\u00f3n<\/strong>! \u00bfPreparadas y preparados para adentraros en la <strong>magia de la ciencia<\/strong>? \ud83e\udd16\ud83c\udf1f<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 tienen en com\u00fan un tornado en una botella, un camale\u00f3n qu\u00edmico y un reloj de yodo? \u00a1Que desaf\u00edan nuestra percepci\u00f3n y nos invitan a explorar el fascinante mundo de la ciencia! En Lauaxeta, celebramos el D\u00eda STEM con actividades que despiertan la curiosidad, fomentan el pensamiento cr\u00edtico y nos acercan a los grandes descubrimientos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":54903,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[371,370,458,459],"class_list":["post-54902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-bachillerato","tag-batxilergoa-es","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/54902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=54902"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/54902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/54903"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=54902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=54902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=54902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}