{"id":55020,"date":"2025-04-01T10:15:58","date_gmt":"2025-04-01T08:15:58","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=55020"},"modified":"2025-04-01T10:15:58","modified_gmt":"2025-04-01T08:15:58","slug":"el-movimiento-es-el-primer-lenguaje-de-la-infancia","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/el-movimiento-es-el-primer-lenguaje-de-la-infancia\/","title":{"rendered":"El movimiento es el primer lenguaje de la infancia"},"content":{"rendered":"<p><strong>En el aula de psicomotricidad, los m\u00e1s txikis juegan, aprenden y crecen<\/strong><\/p>\n<p>El aula de psicomotricidad \ud83d\udfe1\ud83d\udd35\ud83d\udd3a es un espacio muy especial para los ni\u00f1os y ni\u00f1as de Educaci\u00f3n Infantil. All\u00ed, el cuerpo se convierte en su principal herramienta de comunicaci\u00f3n. A trav\u00e9s del movimiento expresan lo que sienten, exploran el mundo y construyen su identidad \ud83e\udd38\u200d\u2642\ufe0f\u2764\ufe0f<\/p>\n<p>No es solo un lugar para jugar, es un aut\u00e9ntico <strong>espacio de aprendizaje<\/strong>:<\/p>\n<p>\ud83c\udf08 <strong>Desarrollan su autonom\u00eda y seguridad<\/strong><br \/>\n\ud83e\udd1d <strong>Viven el respeto, las normas y el turno de palabra<\/strong><br \/>\n\ud83e\udde0 <strong>Mejoran la concentraci\u00f3n y la atenci\u00f3n<\/strong><br \/>\n\ud83d\udcaa <strong>Refuerzan la coordinaci\u00f3n, el equilibrio y el control corporal<\/strong><br \/>\n\ud83d\udcac <strong>Expresan emociones, incluso sin palabras<\/strong><\/p>\n<p>A veces, la sala se llena de materiales variados: telas de colores, cajas gigantes, colchonetas, t\u00faneles, pelotas y cuerdas locas\u2026 Y cada peque explora a su manera, en solitario o en grupo, siempre con <strong>libertad y placer<\/strong> \ud83c\udf1f<\/p>\n<p>Gracias a la psicomotricidad, nuestros txikis aprenden jugando\u2026 y juegan mientras aprenden. Porque el movimiento es, desde el inicio, su camino natural de aprendizaje \ud83d\ude80<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el aula de psicomotricidad, los m\u00e1s txikis juegan, aprenden y crecen El aula de psicomotricidad \ud83d\udfe1\ud83d\udd35\ud83d\udd3a es un espacio muy especial para los ni\u00f1os y ni\u00f1as de Educaci\u00f3n Infantil. All\u00ed, el cuerpo se convierte en su principal herramienta de comunicaci\u00f3n. A trav\u00e9s del movimiento expresan lo que sienten, exploran el mundo y construyen su [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":23325,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[408,434],"class_list":["post-55020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-hh-es","tag-infantil"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/55020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=55020"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/55020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/23325"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=55020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=55020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=55020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}