{"id":55163,"date":"2025-04-08T10:28:28","date_gmt":"2025-04-08T08:28:28","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=55163"},"modified":"2025-04-08T10:33:28","modified_gmt":"2025-04-08T08:33:28","slug":"miradas-cubistas-filosofia-arte-y-emocion-en-infantil","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/miradas-cubistas-filosofia-arte-y-emocion-en-infantil\/","title":{"rendered":"Miradas Cubistas: Filosof\u00eda, arte y emoci\u00f3n en Infantil"},"content":{"rendered":"<p>Este curso, el alumnado de <strong>5 a\u00f1os de Infantil<\/strong> <strong>se ha embarcado en un viaje fascinante: descubrir el mundo del <em>cubismo<\/em> como forma de expresi\u00f3n art\u00edstica y filos\u00f3fica. Y lo han hecho desde el juego, la curiosidad y la emoci\u00f3n de crear.<\/strong><\/p>\n<p>Todo comenz\u00f3 con un folio en blanco y una pregunta: <em>\u00bfY si miramos el mundo desde m\u00e1s de un \u00e1ngulo a la vez?<\/em> As\u00ed empezaron a explorar el lenguaje cubista creando sus propias <em>caras descompuestas<\/em> en papel. \u270f\ufe0f<\/p>\n<p>Poco a poco, sus creaciones fueron creciendo y pasando de los folios a nuevos formatos: <strong>dise\u00f1aron caretas cubistas<\/strong> con las que jugar a ser otras versiones de s\u00ed mismos, y m\u00e1s adelante&#8230; \u00a1convirtieron las cristaleras de sus aulas en aut\u00e9nticos lienzos! \ud83d\uddbc\ufe0f\ud83c\udf08<\/p>\n<p>Este proceso no solo ha sido art\u00edstico, sino profundamente reflexivo. Les hemos invitado a <strong>mirar m\u00e1s all\u00e1<\/strong>, a preguntarse qu\u00e9 ven, qu\u00e9 sienten, y qu\u00e9 les hace pensar una imagen. Un momento clave ha sido la observaci\u00f3n y di\u00e1logo en torno a la obra <em>Gernika<\/em> de Picasso. \ud83d\udcac\ud83d\udd4a\ufe0f<br \/>\n<em>\u00bfQu\u00e9 ves t\u00fa?<\/em><br \/>\n<em>\u00bfPor qu\u00e9 crees que us\u00f3 solo blanco, negro y gris?<\/em><br \/>\n<em>\u00bfQu\u00e9 puede estar pasando en ese cuadro?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"LAUAXETA IKASTOLA- Begirada kubistak!\" width=\"1150\" height=\"647\" src=\"https:\/\/www.youtube.com\/embed\/0AtXTVpfgf8?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/www.lauaxeta.eus\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este curso, el alumnado de 5 a\u00f1os de Infantil se ha embarcado en un viaje fascinante: descubrir el mundo del cubismo como forma de expresi\u00f3n art\u00edstica y filos\u00f3fica. Y lo han hecho desde el juego, la curiosidad y la emoci\u00f3n de crear. Todo comenz\u00f3 con un folio en blanco y una pregunta: \u00bfY si miramos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":55164,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[408,434],"class_list":["post-55163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-hh-es","tag-infantil"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/55163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=55163"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/55163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/55164"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=55163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=55163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=55163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}