{"id":57330,"date":"2025-06-06T11:27:06","date_gmt":"2025-06-06T09:27:06","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=57330"},"modified":"2025-06-06T11:31:43","modified_gmt":"2025-06-06T09:31:43","slug":"escuchar-para-no-olvidar-una-leccion-de-vida-en-4o-de-eso","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/escuchar-para-no-olvidar-una-leccion-de-vida-en-4o-de-eso\/","title":{"rendered":"Escuchar para no olvidar: no a la violencia"},"content":{"rendered":"<p>\ud83d\udd4a\ufe0fHay aprendizajes que no se encuentran en los libros. Experiencias que, por su profundidad y humanidad, dejan una huella duradera en quienes las reciben. En Lauaxeta, cada a\u00f1o el alumnado de 4\u00ba de ESO tiene la gran oportunidad de <strong>escuchar el testimonio directo de una v\u00edctima de la violencia terrorista<\/strong>, en el marco del programa <strong>Adi-Adian<\/strong>.<\/p>\n<p>Este encuentro no solo busca conocer hechos del pasado, sino <strong>entender las emociones, los da\u00f1os, las consecuencias<\/strong>. Porque tambi\u00e9n se aprende de las vivencias ajenas, y aunque afortunadamente nuestras hijas e hijos no han tenido que vivir en primera persona aquella \u00e9poca oscura, <strong>como sociedad no debemos olvidar lo ocurrido<\/strong>. Al contrario, debemos recordarlo para <strong>aprender de los errores<\/strong>, para reafirmarnos en que <strong>la violencia nunca debi\u00f3 existir y nunca ser\u00e1 el camino para defender una idea<\/strong>.<\/p>\n<p>Escuchar de primera mano a quien ha sufrido el dolor permite conectar desde la empat\u00eda y reforzar el valor del respeto, del di\u00e1logo y del trabajo diario como \u00fanicas v\u00edas para construir una sociedad m\u00e1s justa, m\u00e1s pac\u00edfica y m\u00e1s humana.<\/p>\n<p><strong>Gracias por compartir tanto. Gracias por ense\u00f1ar tanto.<\/strong> Porque solo desde la memoria cr\u00edtica podemos construir un futuro mejor. \ud83c\udf31\ud83d\udcac<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd4a\ufe0fHay aprendizajes que no se encuentran en los libros. Experiencias que, por su profundidad y humanidad, dejan una huella duradera en quienes las reciben. En Lauaxeta, cada a\u00f1o el alumnado de 4\u00ba de ESO tiene la gran oportunidad de escuchar el testimonio directo de una v\u00edctima de la violencia terrorista, en el marco del programa [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":57331,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[454,455],"class_list":["post-57330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/57330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=57330"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/57330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/57331"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=57330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=57330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=57330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}