{"id":57994,"date":"2025-06-24T09:32:34","date_gmt":"2025-06-24T07:32:34","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=57994"},"modified":"2025-06-24T09:32:34","modified_gmt":"2025-06-24T07:32:34","slug":"basket-kanpusa-verano-entre-canastas-y-valores","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/basket-kanpusa-verano-entre-canastas-y-valores\/","title":{"rendered":"Basket Kanpusa: verano entre canastas y valores"},"content":{"rendered":"<p>\ud83c\udfc0\u00a0El deporte es mucho m\u00e1s que movimiento, y eso es lo que viven las y los participantes del campamento de Basket de Lauaxeta. Porque aqu\u00ed no solo se entrenan habilidades t\u00e9cnicas, tambi\u00e9n se fomenta el trabajo en equipo, la superaci\u00f3n, la cooperaci\u00f3n y el respeto.<\/p>\n<p data-start=\"548\" data-end=\"729\">Un entorno ideal para quienes disfrutan con el baloncesto, quieren mejorar su juego y, al mismo tiempo, compartir buenos momentos y valores. Aurrera!<\/p>\n<p data-start=\"731\" data-end=\"871\">\ud83d\udc49 M\u00e1s informaci\u00f3n sobre todos los campamentos: <a href=\"https:\/\/www.lauaxeta.eus\/es\/udako-jarduerak\/\" data-start=\"779\" data-end=\"871\">https:\/\/www.lauaxeta.eus\/es\/udako-jarduerak\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83c\udfc0\u00a0El deporte es mucho m\u00e1s que movimiento, y eso es lo que viven las y los participantes del campamento de Basket de Lauaxeta. Porque aqu\u00ed no solo se entrenan habilidades t\u00e9cnicas, tambi\u00e9n se fomenta el trabajo en equipo, la superaci\u00f3n, la cooperaci\u00f3n y el respeto. Un entorno ideal para quienes disfrutan con el baloncesto, quieren [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":57995,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[221],"tags":[458,459],"class_list":["post-57994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-extraescolares-y-de-verano","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/57994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=57994"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/57994\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/57995"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=57994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=57994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=57994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}