{"id":59912,"date":"2025-09-26T09:48:32","date_gmt":"2025-09-26T07:48:32","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=59912"},"modified":"2025-09-26T09:49:45","modified_gmt":"2025-09-26T07:49:45","slug":"patrocinios-en-lauaxeta-sembrando-futuro-juntos","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/patrocinios-en-lauaxeta-sembrando-futuro-juntos\/","title":{"rendered":"Patrocinios en Lauaxeta: sembrando futuro juntos"},"content":{"rendered":"<p>En Lauaxeta creemos que <strong>educar es transformar el futuro<\/strong>. Cada d\u00eda acompa\u00f1amos a m\u00e1s de <strong>1.400 estudiantes y 1.000 familias<\/strong>, contribuyendo a un camino que influir\u00e1 no solo en sus vidas, sino tambi\u00e9n en la sociedad en su conjunto.<\/p>\n<p>Convertirse en patrocinador de Lauaxeta significa mucho m\u00e1s que apoyar proyectos educativos, culturales, deportivos, de sostenibilidad o innovaci\u00f3n. Es <strong>apostar por las nuevas generaciones<\/strong>, dejando huella en su formaci\u00f3n y compartiendo con ellas valores como la <strong>responsabilidad, la creatividad, el compromiso social y el trabajo en equipo<\/strong>.<\/p>\n<p>Adem\u00e1s, tu marca gana visibilidad y se asocia a un proyecto con prop\u00f3sito, alineado con quienes creen que invertir en educaci\u00f3n es invertir en un mundo mejor.<\/p>\n<p>\ud83d\udc49 Te invitamos a descubrir nuestro <a href=\"https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2025\/09\/LAUAXETA-IKASTOLA-Dossier-de-patrocinio-v3-es.pdf\" target=\"_blank\" rel=\"noopener\"><strong>dossier de patrocinios<\/strong><\/a>, donde recogemos algunas propuestas concretas. Aun as\u00ed, queremos escucharte: estamos abiertos a nuevas ideas y a construir, juntas y juntos, el mejor camino para crecer y transformar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Lauaxeta creemos que educar es transformar el futuro. Cada d\u00eda acompa\u00f1amos a m\u00e1s de 1.400 estudiantes y 1.000 familias, contribuyendo a un camino que influir\u00e1 no solo en sus vidas, sino tambi\u00e9n en la sociedad en su conjunto. Convertirse en patrocinador de Lauaxeta significa mucho m\u00e1s que apoyar proyectos educativos, culturales, deportivos, de sostenibilidad [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":59913,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[302,229],"tags":[],"class_list":["post-59912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alianzas","category-gestion"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/59912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=59912"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/59912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/59913"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=59912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=59912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=59912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}