{"id":59956,"date":"2025-09-29T15:38:25","date_gmt":"2025-09-29T13:38:25","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=59956"},"modified":"2025-09-29T15:38:25","modified_gmt":"2025-09-29T13:38:25","slug":"aprendizaje-e-interculturalidad-intercambio-con-dinamarca","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/aprendizaje-e-interculturalidad-intercambio-con-dinamarca\/","title":{"rendered":"Aprendizaje e interculturalidad: intercambio con Dinamarca"},"content":{"rendered":"<p>\ud83c\udf0d Estos d\u00edas, nuestro alumnado de <strong data-start=\"200\" data-end=\"216\">Bachillerato<\/strong> est\u00e1 viviendo una experiencia muy especial: el <strong data-start=\"264\" data-end=\"308\">intercambio con estudiantes de Dinamarca<\/strong>.<\/p>\n<p data-start=\"313\" data-end=\"774\">Gracias a este programa, tanto nuestro alumnado como el que nos visita tienen la oportunidad de:<br data-start=\"409\" data-end=\"412\" \/>\u2728 <strong data-start=\"414\" data-end=\"459\">Aprender desde otra cultura y otro idioma<\/strong>, fomentando la comunicaci\u00f3n y la apertura.<br data-start=\"502\" data-end=\"505\" \/>\u2728 <strong data-start=\"507\" data-end=\"540\">Descubrir nuevas perspectivas<\/strong>, a trav\u00e9s de diferentes costumbres y formas de vida.<br data-start=\"593\" data-end=\"596\" \/>\u2728 <strong data-start=\"598\" data-end=\"631\">Compartir experiencias juntos<\/strong>, tanto en actividades escolares como en el tiempo de ocio.<br data-start=\"690\" data-end=\"693\" \/>\u2728 <strong data-start=\"695\" data-end=\"715\">Trabajar valores<\/strong> como el respeto, la empat\u00eda, el di\u00e1logo y la diversidad.<\/p>\n<p data-start=\"776\" data-end=\"920\">Se trata de una vivencia que va m\u00e1s all\u00e1 de lo acad\u00e9mico: es una oportunidad para <strong data-start=\"858\" data-end=\"914\">crecer como personas y mirar el mundo con otros ojos<\/strong>. \ud83c\udf1f<\/p>\n<p data-start=\"922\" data-end=\"1178\">Durante esta semana tenemos a los estudiantes daneses con nosotros y, pr\u00f3ximamente, ser\u00e1n nuestros alumnos y alumnas quienes viajen a su pa\u00eds para completar el intercambio. Una experiencia que, sin duda, dejar\u00e1 una <strong data-start=\"1137\" data-end=\"1160\">huella muy positiva<\/strong> en todos ellos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf0d Estos d\u00edas, nuestro alumnado de Bachillerato est\u00e1 viviendo una experiencia muy especial: el intercambio con estudiantes de Dinamarca. Gracias a este programa, tanto nuestro alumnado como el que nos visita tienen la oportunidad de:\u2728 Aprender desde otra cultura y otro idioma, fomentando la comunicaci\u00f3n y la apertura.\u2728 Descubrir nuevas perspectivas, a trav\u00e9s de diferentes [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":59957,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[],"class_list":["post-59956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-experiencias-europeas"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/59956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=59956"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/59956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/59957"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=59956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=59956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=59956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}