{"id":60300,"date":"2025-10-09T16:03:59","date_gmt":"2025-10-09T14:03:59","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=60300"},"modified":"2025-10-09T16:03:59","modified_gmt":"2025-10-09T14:03:59","slug":"la-memoria-historica-a-traves-de-la-musica","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/la-memoria-historica-a-traves-de-la-musica\/","title":{"rendered":"La memoria hist\u00f3rica a trav\u00e9s de la m\u00fasica"},"content":{"rendered":"<p data-start=\"1417\" data-end=\"1903\">Durante estos d\u00edas, estudiantes de Lauaxeta han estado en Alemania participando en la <strong data-start=\"1502\" data-end=\"1543\">segunda fase de un proyecto de Memoria hist\u00f3rica a trav\u00e9s de la m\u00fasica.\u00a0<\/strong><br data-start=\"1544\" data-end=\"1547\" \/>Este proyecto, enmarcado en el programa <strong data-start=\"1587\" data-end=\"1630\">Erasmus+ y apoyado por la Uni\u00f3n Europea<\/strong>, se ha desarrollado junto a centros educativos de Francia y Alemania con un objetivo muy especial: <strong data-start=\"1725\" data-end=\"1900\">recuperar y difundir las canciones y composiciones creadas en campos de concentraci\u00f3n y de personas refugiadas durante la Guerra Civil espa\u00f1ola y la Segunda Guerra Mundial<\/strong>.<\/p>\n<p data-start=\"1905\" data-end=\"2108\">El proyecto nos recuerda c\u00f3mo <strong data-start=\"1935\" data-end=\"2046\">la m\u00fasica y el arte se convirtieron en herramientas de resistencia y dignidad en los momentos m\u00e1s dif\u00edciles<\/strong>, manteniendo viva la humanidad incluso en medio del horror.<\/p>\n<p data-start=\"2110\" data-end=\"2541\">En la primera fase, el alumnado visit\u00f3 <strong data-start=\"2149\" data-end=\"2189\">Gernika y el campo de Gurs (Francia)<\/strong>, mientras que en esta segunda fase ha viajado a <strong data-start=\"2238\" data-end=\"2250\">Alemania<\/strong>, conociendo de cerca los <strong data-start=\"2276\" data-end=\"2331\">campos de concentraci\u00f3n, de refugio y de exterminio<\/strong>.<br data-start=\"2332\" data-end=\"2335\" \/>El cierre del proyecto tuvo lugar en <strong data-start=\"2372\" data-end=\"2382\">Berl\u00edn<\/strong>, donde se realiz\u00f3 una <strong data-start=\"2405\" data-end=\"2461\">representaci\u00f3n musical con las canciones recuperadas<\/strong>, como homenaje a quienes mantuvieron viva la esperanza a trav\u00e9s de la m\u00fasica.<\/p>\n<p data-start=\"2543\" data-end=\"2625\">Un puente entre memoria y m\u00fasica, para que nuestro patrimonio no se pierda. \ud83c\udfb5\ud83d\udcab<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante estos d\u00edas, estudiantes de Lauaxeta han estado en Alemania participando en la segunda fase de un proyecto de Memoria hist\u00f3rica a trav\u00e9s de la m\u00fasica.\u00a0Este proyecto, enmarcado en el programa Erasmus+ y apoyado por la Uni\u00f3n Europea, se ha desarrollado junto a centros educativos de Francia y Alemania con un objetivo muy especial: recuperar [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":60301,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[454,455],"class_list":["post-60300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-dbh-es","tag-eso-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/60300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=60300"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/60300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/60301"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=60300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=60300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=60300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}