{"id":60537,"date":"2025-10-16T15:52:42","date_gmt":"2025-10-16T13:52:42","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=60537"},"modified":"2025-10-16T15:52:42","modified_gmt":"2025-10-16T13:52:42","slug":"planes-para-el-fin-de-semana-te-damos-algunas-ideas","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/planes-para-el-fin-de-semana-te-damos-algunas-ideas\/","title":{"rendered":"\u00bfPlanes para el fin de semana? Te damos algunas ideas"},"content":{"rendered":"<p>\ud83c\udf3fEl fin de semana, ese momento en el que queremos desconectar, compartir tiempo de calidad con nuestras hijas e hijos \u2026 pero muchas veces no sabemos qu\u00e9 hacer.<\/p>\n<p>Por eso hemos preparado una selecci\u00f3n de propuestas que no solo entretienen, sino que tambi\u00e9n enriquecen.<\/p>\n<h4>\ud83c\udfaf \u00bfQu\u00e9 encontrar\u00e1s aqu\u00ed?<\/h4>\n<ul>\n<li>Salidas y recorridos para disfrutar de la naturaleza y del entorno.<\/li>\n<li>Experiencias culturales que nos ayudan a abrir la mirada.<\/li>\n<li>Actividades relacionadas con lo que nuestras alumnas y alumnos trabajan en clase.<\/li>\n<li>Opciones adaptadas a cada etapa educativa, para que todas las ni\u00f1as y ni\u00f1os puedan participar y aprender.<\/li>\n<\/ul>\n<p>Queremos que estas sugerencias resulten \u00fatiles en toda su trayectoria escolar.<\/p>\n<p>\ud83d\udc49<a href=\"https:\/\/www.lauaxeta.eus\/wp-content\/uploads\/2022\/09\/LAUAXETA-IKASTOLA-Ekintza-osagarrien-agenda-de-actividades-que-suman-1er-trimestre-2021-2022.pdf\"> Consulta aqu\u00ed<\/a> todas las actividades y elige la que mejor se adapte a tu familia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf3fEl fin de semana, ese momento en el que queremos desconectar, compartir tiempo de calidad con nuestras hijas e hijos \u2026 pero muchas veces no sabemos qu\u00e9 hacer. Por eso hemos preparado una selecci\u00f3n de propuestas que no solo entretienen, sino que tambi\u00e9n enriquecen. \ud83c\udfaf \u00bfQu\u00e9 encontrar\u00e1s aqu\u00ed? Salidas y recorridos para disfrutar de la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":48060,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[686,370,454,455,408,434,458,459],"class_list":["post-60537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escuela-de-padres","tag-bachiller-es","tag-batxilergoa-es","tag-dbh-es","tag-eso-es","tag-hh-es","tag-infantil","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/60537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=60537"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/60537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/48060"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=60537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=60537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=60537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}