{"id":60750,"date":"2025-11-03T17:49:44","date_gmt":"2025-11-03T15:49:44","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=60750"},"modified":"2025-11-03T17:49:44","modified_gmt":"2025-11-03T15:49:44","slug":"nuevas-experiencias-para-seguir-aprendiendo-tambien-en-el-comedor","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/nuevas-experiencias-para-seguir-aprendiendo-tambien-en-el-comedor\/","title":{"rendered":"Nuevas experiencias para seguir aprendiendo tambi\u00e9n en el comedor"},"content":{"rendered":"<p data-start=\"183\" data-end=\"258\">\ud83c\udf7d\ufe0f\u00a0Hoy, el alumnado de 2\u00ba de Bachiller ha tenido ocasi\u00f3n de probar un nuevo sistema en el comedor escolar, que les permite elegir entre dos primeros y dos segundos platos, adem\u00e1s de la opci\u00f3n de quedarse a tomar un caf\u00e9 tras la comida. \u2615<\/p>\n<p data-start=\"498\" data-end=\"871\">M\u00e1s all\u00e1 del men\u00fa, esta iniciativa busca ofrecerles una oportunidad para poner en pr\u00e1ctica la toma de decisiones conscientes, aprendiendo a equilibrar salud, gustos personales y autonom\u00eda. Se trata de un paso m\u00e1s en su proceso de madurez y preparaci\u00f3n para la vida universitaria o laboral, en la que la gesti\u00f3n responsable de sus elecciones ser\u00e1 una herramienta clave. \ud83c\udf31<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf7d\ufe0f\u00a0Hoy, el alumnado de 2\u00ba de Bachiller ha tenido ocasi\u00f3n de probar un nuevo sistema en el comedor escolar, que les permite elegir entre dos primeros y dos segundos platos, adem\u00e1s de la opci\u00f3n de quedarse a tomar un caf\u00e9 tras la comida. \u2615 M\u00e1s all\u00e1 del men\u00fa, esta iniciativa busca ofrecerles una oportunidad para [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":60751,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[229,303],"tags":[371,370],"class_list":["post-60750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestion","category-servicios-complementarios","tag-bachillerato","tag-batxilergoa-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/60750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=60750"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/60750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/60751"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=60750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=60750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=60750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}