{"id":60874,"date":"2025-11-10T10:58:24","date_gmt":"2025-11-10T08:58:24","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=60874"},"modified":"2025-11-10T10:58:24","modified_gmt":"2025-11-10T08:58:24","slug":"justiziazaleak-aprendiendo-a-cuidar-desde-la-empatia","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/justiziazaleak-aprendiendo-a-cuidar-desde-la-empatia\/","title":{"rendered":"Justiziazaleak: aprendiendo a cuidar desde la empat\u00eda"},"content":{"rendered":"<p>\ud83c\udf3f\u00a0En el marco del Bachillerato Internacional, las <strong>agencias del alumnado<\/strong> son grupos de estudiantes que asumen un papel activo en la mejora de su entorno. A trav\u00e9s de ellas, las y los j\u00f3venes identifican necesidades reales, proponen acciones y se implican directamente en causas que promueven un mundo m\u00e1s justo, solidario y sostenible. \ud83c\udf0d<\/p>\n<p>Una de esas agencias es <strong>Justiziazaleak<\/strong>, un grupo comprometido con la <strong>justicia social, la solidaridad y la defensa de los derechos humanos<\/strong>. El <strong>viernes pasado<\/strong> se reunieron con responsables de la <strong>residencia de personas mayores Igurco-Orue<\/strong>, con quienes comenzaron a planificar c\u00f3mo colaborar para <strong>reducir la soledad<\/strong> que muchas veces acompa\u00f1a a las personas mayores. \ud83d\udcac\ud83e\udd1d<\/p>\n<p>El <strong>siguiente paso<\/strong> ser\u00e1 la <strong>visita que realizar\u00e1n a la residencia este viernes<\/strong>, donde podr\u00e1n <strong>compartir tiempo, escuchar historias y crear v\u00ednculos reales<\/strong> con las personas residentes. Una experiencia que, sin duda, les permitir\u00e1 mirar la vida desde otra perspectiva. \ud83c\udf38<\/p>\n<p>A trav\u00e9s de esta iniciativa, el alumnado desarrolla <strong>empat\u00eda, compromiso y responsabilidad social<\/strong>, aprendiendo que cada gesto cuenta cuando se trata de construir una comunidad m\u00e1s humana y solidaria. \ud83d\udcab<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf3f\u00a0En el marco del Bachillerato Internacional, las agencias del alumnado son grupos de estudiantes que asumen un papel activo en la mejora de su entorno. A trav\u00e9s de ellas, las y los j\u00f3venes identifican necesidades reales, proponen acciones y se implican directamente en causas que promueven un mundo m\u00e1s justo, solidario y sostenible. \ud83c\udf0d Una [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":60875,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[302,223,217],"tags":[458,459],"class_list":["post-60874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alianzas","category-ods-y-agenda-2030","category-solidaridad","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/60874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=60874"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/60874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/60875"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=60874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=60874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=60874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}