{"id":61059,"date":"2025-11-20T12:42:10","date_gmt":"2025-11-20T10:42:10","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=61059"},"modified":"2025-11-20T12:42:10","modified_gmt":"2025-11-20T10:42:10","slug":"hemos-estado-en-koopaketa-gazte-eta-kooperatibismoaren-topaketa","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/hemos-estado-en-koopaketa-gazte-eta-kooperatibismoaren-topaketa\/","title":{"rendered":"Hemos estado en Koopaketa: gazte eta kooperatibismoaren topaketa"},"content":{"rendered":"<p data-start=\"102\" data-end=\"219\">\ud83e\udd1d\u00a0Hoy, <strong data-start=\"226\" data-end=\"245\">20 de noviembre<\/strong>, estamos participando en <a href=\"https:\/\/koopaketa.eus\/\" target=\"_blank\" rel=\"noopener\"><strong>Koopapeka: Gazte Kooperatibisten Lehen Topaketa<\/strong><\/a>, el primer encuentro de j\u00f3venes cooperativistas celebrado en Bilbao y organizado por Koopaketa. Una jornada que re\u00fane a estudiantes, j\u00f3venes profesionales y centros comprometidos con el modelo cooperativo y su futuro.<\/p>\n<p data-start=\"531\" data-end=\"1041\">Desde <strong data-start=\"537\" data-end=\"558\">Lauaxeta Ikastola<\/strong> hemos acudido para compartir nuestra visi\u00f3n, aprender de otras experiencias y seguir fortaleciendo el papel que el cooperativismo tiene en nuestro proyecto educativo.<br data-start=\"725\" data-end=\"728\" \/>Adem\u00e1s, nuestra compa\u00f1era <strong data-start=\"754\" data-end=\"771\">Miren Munitis<\/strong>, docente de Lauaxeta, interviene en la primera ponencia de la jornada bajo el t\u00edtulo <em data-start=\"857\" data-end=\"902\">\u00abKooperatibismo eredua, begi gazteen bidez\u00bb<\/em> (\u201cEl modelo cooperativo a trav\u00e9s de ojos j\u00f3venes\u201d), aportando la mirada de la educaci\u00f3n y del trabajo que realizamos con nuestro alumnado.<\/p>\n<h3 data-start=\"1043\" data-end=\"1089\">\ud83c\udf1f \u00bfQu\u00e9 nos est\u00e1 aportando esta jornada?<\/h3>\n<ul data-start=\"1090\" data-end=\"1514\">\n<li data-start=\"1090\" data-end=\"1222\">\n<p data-start=\"1092\" data-end=\"1222\">Un espacio para reflexionar sobre <strong data-start=\"1126\" data-end=\"1170\">c\u00f3mo viven los j\u00f3venes el cooperativismo<\/strong> y qu\u00e9 necesitan para sentirse parte activa de \u00e9l.<\/p>\n<\/li>\n<li data-start=\"1223\" data-end=\"1391\">\n<p data-start=\"1225\" data-end=\"1391\">La oportunidad de compartir con entidades referentes c\u00f3mo se est\u00e1 impulsando que el cooperativismo sea <strong data-start=\"1357\" data-end=\"1388\">m\u00e1s joven y con m\u00e1s j\u00f3venes<\/strong>.<\/p>\n<\/li>\n<li data-start=\"1392\" data-end=\"1514\">\n<p data-start=\"1394\" data-end=\"1514\">Din\u00e1micas, conversaciones y actividades que nos permiten seguir integrando estos valores en el d\u00eda a d\u00eda de la ikastola.<\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"1516\" data-end=\"1543\">\ud83e\udd32 Nuestro compromiso<\/h3>\n<p data-start=\"1544\" data-end=\"1850\">Participar en esta jornada refuerza nuestra convicci\u00f3n de que el cooperativismo no es solo un modelo econ\u00f3mico, sino una forma de educar, convivir y construir comunidad.<br data-start=\"1713\" data-end=\"1716\" \/>En Lauaxeta seguiremos facilitando espacios donde el alumnado pueda <strong data-start=\"1784\" data-end=\"1828\">participar, decidir, crear y transformar<\/strong> desde la cooperaci\u00f3n.<\/p>\n<p data-start=\"1852\" data-end=\"1954\">Eskerrik asko a la organizaci\u00f3n y a todas las personas participantes por esta experiencia inspiradora.<\/p>\n<p data-start=\"1956\" data-end=\"2005\">Seguimos construyendo futuro, juntas y juntos. \ud83d\udc9b<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83e\udd1d\u00a0Hoy, 20 de noviembre, estamos participando en Koopapeka: Gazte Kooperatibisten Lehen Topaketa, el primer encuentro de j\u00f3venes cooperativistas celebrado en Bilbao y organizado por Koopaketa. Una jornada que re\u00fane a estudiantes, j\u00f3venes profesionales y centros comprometidos con el modelo cooperativo y su futuro. Desde Lauaxeta Ikastola hemos acudido para compartir nuestra visi\u00f3n, aprender de otras [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":61060,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[225,229],"tags":[],"class_list":["post-61059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conferencias-e-intervenciones","category-gestion"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/61059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=61059"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/61059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/61060"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=61059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=61059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=61059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}