{"id":61456,"date":"2025-12-02T10:50:48","date_gmt":"2025-12-02T08:50:48","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=61456"},"modified":"2025-12-02T10:50:48","modified_gmt":"2025-12-02T08:50:48","slug":"nuestro-coro-en-el-espectaculo-ei-bilbao-en-miribilla","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/nuestro-coro-en-el-espectaculo-ei-bilbao-en-miribilla\/","title":{"rendered":"Nuestro coro en el espect\u00e1culo \u00a1Ei Bilbao! en Miribilla"},"content":{"rendered":"<p>\ud83c\udfb6\u00a0El pasado <strong>28 de noviembre<\/strong>, un grupo de <strong>32 estudiantes del coro de la ikastola<\/strong> tuvo la oportunidad de vivir una bonita experiencia: <strong>participar en el espect\u00e1culo <\/strong><em><strong>\u00a1Ei Bilbao!<\/strong><\/em><strong> celebrado en Miribilla<\/strong>.<\/p>\n<p>Fue una jornada llena de m\u00fasica, emoci\u00f3n y aprendizaje. Nuestros alumnos y alumnas disfrutaron del escenario, compartieron espacio con otros coros y artistas, y demostraron todo el trabajo y la ilusi\u00f3n que ponen cada semana en los ensayos.<\/p>\n<p>Adem\u00e1s de la actuaci\u00f3n, esta experiencia les permiti\u00f3 crecer como grupo, fortalecer su confianza y vivir desde dentro la magia de un gran evento cultural en Bilbao.<\/p>\n<p>Zorionak a todos y todas por el esfuerzo y por representar tan bien a la ikastola. \ud83d\udc99\ud83c\udfa4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83c\udfb6\u00a0El pasado 28 de noviembre, un grupo de 32 estudiantes del coro de la ikastola tuvo la oportunidad de vivir una bonita experiencia: participar en el espect\u00e1culo \u00a1Ei Bilbao! celebrado en Miribilla. Fue una jornada llena de m\u00fasica, emoci\u00f3n y aprendizaje. Nuestros alumnos y alumnas disfrutaron del escenario, compartieron espacio con otros coros y artistas, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":61457,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[221,220],"tags":[458,459],"class_list":["post-61456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades-extraescolares-y-de-verano","category-eventos-y-celebraciones","tag-lh-es","tag-primaria-es"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/61456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=61456"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/61456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/61457"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=61456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=61456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=61456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}