{"id":61664,"date":"2025-12-15T16:50:34","date_gmt":"2025-12-15T14:50:34","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=61664"},"modified":"2025-12-15T16:51:22","modified_gmt":"2025-12-15T14:51:22","slug":"creciendo-como-txapeldunes-un-encuentro-deportivo-muy-especial-en-lauaxeta-ikastola","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/creciendo-como-txapeldunes-un-encuentro-deportivo-muy-especial-en-lauaxeta-ikastola\/","title":{"rendered":"Creciendo como txapeldunes: un encuentro deportivo muy especial en Lauaxeta Ikastola"},"content":{"rendered":"<p data-start=\"201\" data-end=\"437\">Este fin de semana en <strong data-start=\"223\" data-end=\"244\">Lauaxeta Ikastola<\/strong> vivimos una jornada realmente especial: \u00a1un e<em data-start=\"289\" data-end=\"322\">ncuentro deportivo de txapeldunes<\/em> que reuni\u00f3 a la gela de 4 y 5 a\u00f1os con gran entusiasmo y esp\u00edritu deportivo!<\/p>\n<p data-start=\"439\" data-end=\"739\">Fue una oportunidad para que los ni\u00f1os de 5 a\u00f1os aprendieran valores que van m\u00e1s all\u00e1 del marcador.<\/p>\n<ul data-start=\"936\" data-end=\"1355\">\n<li data-start=\"936\" data-end=\"1013\">\n<p data-start=\"938\" data-end=\"1013\">\u26bd <strong data-start=\"940\" data-end=\"962\">Trabajo en equipo:<\/strong> Aprender a entenderse y apoyarse entre compa\u00f1eros.<\/p>\n<\/li>\n<li data-start=\"1014\" data-end=\"1125\">\n<p data-start=\"1016\" data-end=\"1125\">\ud83d\udcaa <strong data-start=\"1019\" data-end=\"1048\">Esfuerzo y perseverancia:<\/strong> La importancia de intentarlo, aprender de los errores y volver a levantarse.<\/p>\n<\/li>\n<li data-start=\"1126\" data-end=\"1219\">\n<p data-start=\"1128\" data-end=\"1219\">\ud83e\udd1d <strong data-start=\"1131\" data-end=\"1158\">Respeto y deportividad:<\/strong> Valorar al rival, al \u00e1rbitro y a los compa\u00f1eros con respeto.<\/p>\n<\/li>\n<li data-start=\"1220\" data-end=\"1355\">\n<p data-start=\"1222\" data-end=\"1355\">\ud83d\ude04 <strong data-start=\"1225\" data-end=\"1248\">Diversi\u00f3n y pasi\u00f3n:<\/strong> Disfrutar del deporte y pasarlo en grande movi\u00e9ndose y compartiendo.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1729\" data-end=\"2042\">Queremos dar las gracias a todas las familias, profesorado y estudiantes que hicieron posible este evento. Aurrera!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana en Lauaxeta Ikastola vivimos una jornada realmente especial: \u00a1un encuentro deportivo de txapeldunes que reuni\u00f3 a la gela de 4 y 5 a\u00f1os con gran entusiasmo y esp\u00edritu deportivo! Fue una oportunidad para que los ni\u00f1os de 5 a\u00f1os aprendieran valores que van m\u00e1s all\u00e1 del marcador. \u26bd Trabajo en equipo: [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":61665,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-61664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/61664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=61664"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/61664\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/61665"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=61664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=61664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=61664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}