{"id":62473,"date":"2026-02-05T11:49:11","date_gmt":"2026-02-05T09:49:11","guid":{"rendered":"https:\/\/www.lauaxeta.eus\/?p=62473"},"modified":"2026-02-05T13:15:05","modified_gmt":"2026-02-05T11:15:05","slug":"aprender-para-comprender-una-charla-sobre-el-autismo","status":"publish","type":"post","link":"https:\/\/www.lauaxeta.eus\/es\/aprender-para-comprender-una-charla-sobre-el-autismo\/","title":{"rendered":"Aprender para comprender: una charla sobre el autismo"},"content":{"rendered":"<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"bcef5a82-80af-4187-b388-6de0311cabed\" data-testid=\"conversation-turn-8\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto [--thread-content-margin:--spacing(4)] @w-sm\/main:[--thread-content-margin:--spacing(6)] @w-lg\/main:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"cb39ca69-d7ca-439d-8bcb-3dae65b7693e\" data-message-model-slug=\"gpt-5-2\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word light markdown-new-styling\">\n<p data-start=\"216\" data-end=\"295\">\ud83d\udc99\u00a0Esta semana hemos vivido un momento muy especial en <strong data-start=\"349\" data-end=\"390\"><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Lauaxeta Ikastola<\/span><\/span><\/strong>, de esos que dejan huella y nos ayudan a seguir creciendo como comunidad educativa.<\/p>\n<p data-start=\"476\" data-end=\"690\"><strong>Un alumno y su aita han querido acercarse para compartir su experiencia y conocimientos sobre el<\/strong> <strong data-start=\"579\" data-end=\"590\">autismo<\/strong>, con el objetivo de fomentar la comprensi\u00f3n, la empat\u00eda y la mirada inclusiva en nuestro d\u00eda a d\u00eda.<\/p>\n<p data-start=\"692\" data-end=\"1039\">La iniciativa comenz\u00f3 con una charla dirigida a las <strong data-start=\"744\" data-end=\"765\">alumnas y alumnos<\/strong>, adaptada a su edad y a su manera de entender el mundo. A trav\u00e9s de ejemplos cercanos y explicaciones claras, se les ayud\u00f3 a comprender que todas las personas somos diferentes, que cada una se comunica y siente a su manera, y que esas diferencias nos enriquecen como grupo.<\/p>\n<p data-start=\"1041\" data-end=\"1379\">Tras este primer encuentro con el alumnado, el aita quiso dar un paso m\u00e1s y <strong data-start=\"1117\" data-end=\"1183\">compartir la charla con el claustro de profesores y profesoras<\/strong>. Fue un espacio de escucha, reflexi\u00f3n y aprendizaje mutuo, en el que se habl\u00f3 no solo del autismo, sino tambi\u00e9n de la importancia de acompa\u00f1ar desde el respeto, la sensibilidad y el conocimiento.<\/p>\n<p data-start=\"1381\" data-end=\"1639\">Para nuestro equipo educativo, este tipo de encuentros son una oportunidad valiosa para seguir form\u00e1ndose y para reforzar nuestro compromiso con una educaci\u00f3n <strong data-start=\"1540\" data-end=\"1574\">inclusiva, consciente y humana<\/strong>, donde cada ni\u00f1o y ni\u00f1a pueda sentirse comprendido y acompa\u00f1ado.<\/p>\n<p data-start=\"1641\" data-end=\"1925\">Desde la ikastola queremos agradecer de coraz\u00f3n la generosidad de este aita por compartir su vivencia y por ayudarnos a mirar con m\u00e1s profundidad, empat\u00eda y responsabilidad. Porque educar no es solo ense\u00f1ar contenidos, sino tambi\u00e9n <strong data-start=\"1873\" data-end=\"1921\">aprender a convivir, a comprender y a cuidar<\/strong>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udc99\u00a0Esta semana hemos vivido un momento muy especial en Lauaxeta Ikastola, de esos que dejan huella y nos ayudan a seguir creciendo como comunidad educativa. Un alumno y su aita han querido acercarse para compartir su experiencia y conocimientos sobre el autismo, con el objetivo de fomentar la comprensi\u00f3n, la empat\u00eda y la mirada inclusiva [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":62476,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[224],"tags":[],"class_list":["post-62473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escuela-de-padres"],"_links":{"self":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/62473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/comments?post=62473"}],"version-history":[{"count":0,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/posts\/62473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media\/62476"}],"wp:attachment":[{"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/media?parent=62473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/categories?post=62473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauaxeta.eus\/es\/wp-json\/wp\/v2\/tags?post=62473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}